{"id":14587,"date":"2018-02-15T23:34:01","date_gmt":"2018-02-15T23:34:01","guid":{"rendered":"https:\/\/fcmanrique.org\/fcm-obra\/giuliano-mauri-bozzolo-2\/"},"modified":"2022-10-10T09:55:59","modified_gmt":"2022-10-10T09:55:59","slug":"giuliano-mauri-bozzolo-2","status":"publish","type":"fcm_obra","link":"https:\/\/fcmanrique.org\/de\/fcm-obra\/giuliano-mauri-bozzolo-2\/","title":{"rendered":"Giuliano Mauri. Bozzolo"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-de\">Leider ist der Eintrag nur auf <a href=\"https:\/\/fcmanrique.org\/es\/wp-json\/wp\/v2\/fcm_obra\/14587\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"ES\">ES<\/a> verf\u00fcgbar.<\/p><p><strong>Programa &#8222;Residencia-Taller. Artistas en residencia&#8220; organizado por la Fundaci\u00f3n C\u00e9sar Manrique<\/strong><\/p>\n<p>Giuliano Mauri (Loddi Vechio, Italia) particip\u00f3 en el programa &#8222;Residencia-Taller. Artistas en residencia&#8220; en el a\u00f1o 2004. Permaneci\u00f3 en la isla del 29 de enero hasta el 12 de febrero.<\/p>\n<p>La FCM incorpor\u00f3 tres de sus obras a la colecci\u00f3n Arte-Naturaleza, una de ellas realizada por el artista durante su estancia en Lanzarote.<\/p>\n<p>La exposici\u00f3n de Giuliano Mauri en la FCM permaneci\u00f3 del 16 de junio al 18 de septiembre de 2005, en la que se mostraron 22 esculturas y 16 maquetas del artista.<\/p>","protected":false},"featured_media":14588,"parent":0,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"tipo_de_obra":[],"coleccion_de_obra":[21],"class_list":["post-14587","fcm_obra","type-fcm_obra","status-publish","has-post-thumbnail","hentry","coleccion_de_obra-arte-y-naturaleza"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/fcm_obra\/14587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/fcm_obra"}],"about":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/types\/fcm_obra"}],"version-history":[{"count":1,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/fcm_obra\/14587\/revisions"}],"predecessor-version":[{"id":23155,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/fcm_obra\/14587\/revisions\/23155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/media\/14588"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/media?parent=14587"}],"wp:term":[{"taxonomy":"tipo_de_obra","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/tipo_de_obra?post=14587"},{"taxonomy":"coleccion_de_obra","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/coleccion_de_obra?post=14587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}