{"id":4089,"date":"2008-05-06T00:00:00","date_gmt":"2008-05-06T00:00:00","guid":{"rendered":"https:\/\/fcmanrique.org\/2008\/05\/06\/5-de-junio-a-21-de-septiembre-exposicion-jan-hendrix-malpais\/?lang=es"},"modified":"2022-09-13T12:02:32","modified_gmt":"2022-09-13T12:02:32","slug":"5-de-junio-a-21-de-septiembre-exposicion-jan-hendrix-malpais","status":"publish","type":"post","link":"https:\/\/fcmanrique.org\/de\/5-de-junio-a-21-de-septiembre-exposicion-jan-hendrix-malpais\/","title":{"rendered":"5 de junio a 21 de septiembre. Exposici\u00f3n. Jan Hendrix. Malpa\u00eds"},"content":{"rendered":"<p><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El 5 de junio, D&iacute;a Mundial del Medio Ambiente, se inaugurar&aacute; en la sede de la FCM de Taro de Tah&iacute;che y en la sala Jos&eacute; Saramago de Arrecife una exposici&oacute;n dedicada a Jan Hendrix, artista holand&eacute;s con residencia en M&eacute;xico, que trabaja en obra gr&aacute;fica, sobre planchas de metal de gran formato, inspirada en la presentaci&oacute;n de sombras de formas org&aacute;nicas. Elementos como flores, tallos, ra&iacute;ces y hojas, hacen de su propuesta una mirada po&eacute;tica hacia el paisaje natural. La muestra podr&aacute; contemplarse en ambas salas hasta el 21 de septiembre.<span > <\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">A finales del a&ntilde;o 2006, en el marco del programa <em >Artistas en Residencia<\/em> de la FCM, Jan Hendrix, considerado como uno de los maestros de la t&eacute;cnica de la serigraf&iacute;a y del grabado, se desplaz&oacute; a Lanzarote, y comenz&oacute; los trabajos para la muestra, <\/span><span style=\"ofont-size: 10pt; ofont-family: Arial;\">que cuenta con la colaboraci&oacute;n del Gobierno de Canarias<\/span><span style=\"ofont-size: 10pt; ofont-family: Arial;\">. Hendrix permaneci&oacute; en la Isla durante dieciseis d&iacute;as, y organiz&oacute; su centro de operaciones en el estudio que la FCM puso a su disposici&oacute;n en Caleta en Famara, desde donde realizaba caminatas para recoger materiales org&aacute;nicos y tomar notas.<o:p> <br \/><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El resultado de ese trabajo, con posterioridad desarrollado en M&eacute;xico y Madrid, podr&aacute; verse ahora en dos salas de la FCM. En la sala Jos&eacute; Saramago de Arrecife se instalar&aacute; una gran pieza escult&oacute;rica central, consistente en una espiral transitable para el p&uacute;blico, concebida como una celos&iacute;a vegetal, a partir de motivos org&aacute;nicos del paisaje de Lanzarote. Por otra parte, ya en la sala Taro de la sede de la FCM en Tah&iacute;che, podr&aacute;n verse dibujos y, en particular, una serie de grabados sobre paisajes y elementos de la cubierta vegetal de la isla.<o:p> <br \/><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">Con ocasi&oacute;n de la muestra, la FCM editar&aacute; un cat&aacute;logo que documentar&aacute; los contenidos expuestos al p&uacute;blico.<o:p> <br \/><\/o:p><\/span><\/p>\n<p><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El programa <em >Artistas en Residencia<\/em>, que ya ha contado con la participaci&oacute;n de los creadores Nils-Udo, Thomas Joshua Cooper, Miguel &Aacute;ngel Blanco, Axel H&uuml;tte, Hamish Fulton,<span >&nbsp; <\/span>Giuliano Mauri o Gilles Cl&eacute;ment, constituye el eje central de la pol&iacute;tica de exposiciones temporales y de la colecci&oacute;n de arte de la FCM, cohesionando los aspectos pl&aacute;sticos de la Instituci&oacute;n en el &aacute;mbito de su programaci&oacute;n y en el de su pol&iacute;tica de adquisiciones. El programa consiste en invitar a artistas del circuito internacional a desarrollar proyectos relacionados con la Naturaleza y el paisaje de Lanzarote. Posteriormente algunas de las piezas de esos proyectos son adquiridas por la Instituci&oacute;n, pasando a formar parte de su colecci&oacute;n <em >Arte-Naturaleza<\/em>. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El 5 de junio, D&iacute;a Mundial del Medio Ambiente, se inaugurar&aacute; en la sede de la FCM de Taro de Tah&iacute;che y en la sala Jos&eacute; Saramago de Arrecife una exposici&oacute;n dedicada a Jan Hendrix, artista holand&eacute;s con residencia en M&eacute;xico, que trabaja en obra gr&aacute;fica, sobre planchas de metal de gran formato, inspirada en la presentaci&oacute;n de sombras de formas org&aacute;nicas. Elementos como flores, tallos, ra&iacute;ces y hojas, hacen de su propuesta una mirada po&eacute;tica hacia el paisaje natural. La muestra podr&aacute; contemplarse en ambas salas hasta el 21 de septiembre.<span > <\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">A finales del a&ntilde;o 2006, en el marco del programa <em >Artistas en Residencia<\/em> de la FCM, Jan Hendrix, considerado como uno de los maestros de la t&eacute;cnica de la serigraf&iacute;a y del grabado, se desplaz&oacute; a Lanzarote, y comenz&oacute; los trabajos para la muestra, <\/span><span style=\"ofont-size: 10pt; ofont-family: Arial;\">que cuenta con la colaboraci&oacute;n del Gobierno de Canarias<\/span><span style=\"ofont-size: 10pt; ofont-family: Arial;\">. Hendrix permaneci&oacute; en la Isla durante dieciseis d&iacute;as, y organiz&oacute; su centro de operaciones en el estudio que la FCM puso a su disposici&oacute;n en Caleta en Famara, desde donde realizaba caminatas para recoger materiales org&aacute;nicos y tomar notas.<o:p> <br \/><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El resultado de ese trabajo, con posterioridad desarrollado en M&eacute;xico y Madrid, podr&aacute; verse ahora en dos salas de la FCM. En la sala Jos&eacute; Saramago de Arrecife se instalar&aacute; una gran pieza escult&oacute;rica central, consistente en una espiral transitable para el p&uacute;blico, concebida como una celos&iacute;a vegetal, a partir de motivos org&aacute;nicos del paisaje de Lanzarote. Por otra parte, ya en la sala Taro de la sede de la FCM en Tah&iacute;che, podr&aacute;n verse dibujos y, en particular, una serie de grabados sobre paisajes y elementos de la cubierta vegetal de la isla.<o:p> <br \/><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">Con ocasi&oacute;n de la muestra, la FCM editar&aacute; un cat&aacute;logo que documentar&aacute; los contenidos expuestos al p&uacute;blico.<o:p> <br \/><\/o:p><\/span><\/p>\n<p><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El programa <em >Artistas en Residencia<\/em>, que ya ha contado con la participaci&oacute;n de los creadores Nils-Udo, Thomas Joshua Cooper, Miguel &Aacute;ngel Blanco, Axel H&uuml;tte, Hamish Fulton,<span >&nbsp; <\/span>Giuliano Mauri o Gilles Cl&eacute;ment, constituye el eje central de la pol&iacute;tica de exposiciones temporales y de la colecci&oacute;n de arte de la FCM, cohesionando los aspectos pl&aacute;sticos de la Instituci&oacute;n en el &aacute;mbito de su programaci&oacute;n y en el de su pol&iacute;tica de adquisiciones. El programa consiste en invitar a artistas del circuito internacional a desarrollar proyectos relacionados con la Naturaleza y el paisaje de Lanzarote. Posteriormente algunas de las piezas de esos proyectos son adquiridas por la Instituci&oacute;n, pasando a formar parte de su colecci&oacute;n <em >Arte-Naturaleza<\/em>. <\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>El 5 de junio, D&iacute;a Mundial del Medio Ambiente, se inaugurar&aacute; en la sede de la FCM de Taro de Tah&iacute;che y en la sala Jos&eacute; Saramago de Arrecife una exposici&oacute;n dedicada a Jan Hendrix, artista holand&eacute;s con residencia en M&eacute;xico, que trabaja en obra gr&aacute;fica, sobre planchas de metal de gran formato, inspirada en&#8230; <a href=\"https:\/\/fcmanrique.org\/de\/5-de-junio-a-21-de-septiembre-exposicion-jan-hendrix-malpais\/\" class=\"readmore\">Contin\u00faa leyendo \u2192<\/a><\/p>\n","protected":false},"author":1,"featured_media":4091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,77,4],"tags":[],"class_list":["post-4089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sitio-antiguo","category-prensa","category-expirados"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/comments?post=4089"}],"version-history":[{"count":4,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4089\/revisions"}],"predecessor-version":[{"id":22818,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4089\/revisions\/22818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/media\/4091"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/media?parent=4089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/categories?post=4089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/tags?post=4089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}