{"id":4099,"date":"2008-04-17T00:00:00","date_gmt":"2008-04-17T00:00:00","guid":{"rendered":"https:\/\/fcmanrique.org\/2008\/04\/17\/la-fcm-presente-en-el-i-congreso-internacional-los-museos-en-la-educacion-celebrado-en-madrid\/?lang=es"},"modified":"2022-09-13T11:59:55","modified_gmt":"2022-09-13T11:59:55","slug":"la-fcm-presente-en-el-i-congreso-internacional-los-museos-en-la-educacion-celebrado-en-madrid","status":"publish","type":"post","link":"https:\/\/fcmanrique.org\/de\/la-fcm-presente-en-el-i-congreso-internacional-los-museos-en-la-educacion-celebrado-en-madrid\/","title":{"rendered":"La FCM, presente en el <em>I Congreso Internacional: Los museos en la educaci\u00f3n<\/em>, celebrado en Madrid"},"content":{"rendered":"<p><\/p>\n<p lang=\"es-ES\" style=\"margin-bottom: 0cm; line-height: 0.56cm; widows: 0; orphans: 0;\"> <font color=\"#000000\"><font face=\"Geneva, Arial, sans-serif\"><font size=\"2\">Se trata del primer congreso de estas caracter&iacute;sticas que se celebra en Espa&ntilde;a y para ello, el Museo Thyssen-Bornemisza ha invitado a ocho profesionales para las principales ponencias y a m&aacute;s de una veintena para las comunicaciones y los debates. Organizado en cuatro bloques de ponencias, el I Congreso Internacional: Los museos en la Educaci&oacute;n trat&oacute; aspectos relacionados con la ense&ntilde;anza y el conocimiento del arte; la investigaci&oacute;n desde el museo y desde la universidad; las cuestiones metodol&oacute;gicas en las propuestas educativas; y el museo y su relaci&oacute;n con el entorno. En este &uacute;ltimo bloque es para el que el Museo Thyssen-Bornemisza curs&oacute; invitaci&oacute;n a la Fundaci&oacute;n C&eacute;sar Manrique, que estuvo representada por Alfredo D&iacute;az, Jefe del Departamento Pedag&oacute;gico, quien present&oacute; la ponencia titulada El Museo y su entorno natural.<\/font><\/font><\/font><\/p>\n<p lang=\"es-ES\" style=\"margin-bottom: 0cm; line-height: 0.56cm; widows: 0; orphans: 0;\"> <font color=\"#000000\"><font face=\"Geneva, Arial, sans-serif\"><font size=\"2\">Los otros siete ponentes a los que el Museo Thyssen-Bornemisza invit&oacute; para las ponencias centrales representan al Metropolitan Museum of Art (Nueva York), y a las Universidades de Stanford (Palo Alto, California), Leicester (Reino Unido), Wuppertal (Alemania), Barcelona, Girona y a la Universidad Southern California.<\/font><\/font><\/font><\/p>\n<p lang=\"es-ES\" style=\"margin-bottom: 0cm; line-height: 0.56cm; widows: 0; orphans: 0;\"> <font color=\"#000000\"><font face=\"Geneva, Arial, sans-serif\"><font size=\"2\">En los debates y paneles de comunicaci&oacute;n participaron especialistas del Museo Patio Herreriano de Valladolid, de la Universidad de Navarra, del Museo de Arte Reina Sof&iacute;a, del MUSAC de Le&oacute;n, de la Pinacoteca del Estado de Sao Paulo, de la National Gallery of Art, del Museo de Arte de Lima o del Museo de Bellas Artes de La Habana, entre otros.<\/font><\/font><\/font><\/p>\n<p lang=\"es-ES\" style=\"margin-bottom: 0cm; line-height: 0.56cm; widows: 0; orphans: 0;\"> <font color=\"#000000\"><font face=\"Geneva, Arial, sans-serif\"><font size=\"2\">Un total de 200 profesionales del &aacute;mbito de la educaci&oacute;n en museos y la formaci&oacute;n de educadores participaron en este I Congreso Internacional de los museos en la Educaci&oacute;n.<\/font><\/font><\/font><\/p>\n<p lang=\"es-ES\" style=\"margin-bottom: 0cm; line-height: 0.56cm; widows: 0; orphans: 0;\"> <font color=\"#000000\"><font face=\"Geneva, Arial, sans-serif\"><font size=\"2\">Todas las sesiones pueden ser consultadas en formato video streaming a trav&eacute;s de la web del congreso en <a href=\"http:\/\/www.educathyssen.org\">www.educathyssen.org<\/a><\/font><\/font><\/font><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p lang=\"es-ES\" style=\"margin-bottom: 0cm; line-height: 0.56cm; widows: 0; orphans: 0;\">\n<p lang=\"es-ES\" style=\"margin-bottom: 0cm; line-height: 0.46cm; widows: 0; orphans: 0;\"> <font color=\"#000000\"><font face=\"Geneva, Arial, sans-serif\"><font size=\"2\">Profesionales de museos como el Metropolitan Museum de Nueva York, la National Gallery of Art de Washington o el Museo Thyssen-Bornemisza de Madrid, y destacados profesores de distintas universidades, analizaron las innovaciones metodol&oacute;gicas y las m&aacute;s recientes v&iacute;as de investigaci&oacute;n en  materia de comunicaci&oacute;n en los museos.<\/font><\/font><\/font><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,77,4],"tags":[],"class_list":["post-4099","post","type-post","status-publish","format-standard","hentry","category-sitio-antiguo","category-prensa","category-expirados"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/comments?post=4099"}],"version-history":[{"count":3,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4099\/revisions"}],"predecessor-version":[{"id":22815,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4099\/revisions\/22815"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/media?parent=4099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/categories?post=4099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/tags?post=4099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}