{"id":4129,"date":"2008-01-29T00:00:00","date_gmt":"2008-01-29T00:00:00","guid":{"rendered":"https:\/\/fcmanrique.org\/2008\/01\/29\/valoracion-del-auto-del-tribunal-supremo-que-ratifica-la-sentencia-del-aparcamiento-del-parque-islas-canarias\/?lang=es"},"modified":"2022-09-13T10:05:11","modified_gmt":"2022-09-13T10:05:11","slug":"valoracion-del-auto-del-tribunal-supremo-que-ratifica-la-sentencia-del-aparcamiento-del-parque-islas-canarias","status":"publish","type":"post","link":"https:\/\/fcmanrique.org\/de\/valoracion-del-auto-del-tribunal-supremo-que-ratifica-la-sentencia-del-aparcamiento-del-parque-islas-canarias\/","title":{"rendered":"Valoraci\u00f3n del auto del Tribunal Supremo que ratifica la sentencia del aparcamiento del parque Islas Canarias"},"content":{"rendered":"<p><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El reciente auto del Tribunal Supremo hace firme la sentencia emitida el 17 de marzo del pasado a&ntilde;o por el TSJC, que anul&oacute; las licencias de construcci&oacute;n y apertura del aparcamiento subterr&aacute;neo del parque Islas Canarias, al entender que la concesi&oacute;n de las mismas por la Comisi&oacute;n de Gobierno del Ayuntamiento de Arrecife vulner&oacute; la normativa municipal y la de Puertos.<\/p>\n<p>M&aacute;s informaci&oacute;n en la nota de prensa.<\/span><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El reciente auto del Tribunal Supremo hace firme la sentencia emitida el 17 de marzo del pasado a&ntilde;o por el TSJC, que anul&oacute; las licencias de construcci&oacute;n y apertura del aparcamiento subterr&aacute;neo del parque Islas Canarias, al entender que la concesi&oacute;n de las mismas por la Comisi&oacute;n de Gobierno del Ayuntamiento de Arrecife vulner&oacute; la normativa municipal y la de Puertos.<\/p>\n<p>M&aacute;s informaci&oacute;n en la nota de prensa.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El reciente auto del Tribunal Supremo hace firme la sentencia emitida el 17 de marzo del pasado a&ntilde;o por el TSJC, que anul&oacute; las licencias de construcci&oacute;n y apertura del aparcamiento subterr&aacute;neo del parque Islas Canarias, al entender que la concesi&oacute;n de las mismas por la Comisi&oacute;n de Gobierno del Ayuntamiento de Arrecife vulner&oacute; la normativa municipal y la de Puertos.<br \/><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,77,4],"tags":[],"class_list":["post-4129","post","type-post","status-publish","format-standard","hentry","category-sitio-antiguo","category-prensa","category-expirados"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/comments?post=4129"}],"version-history":[{"count":4,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4129\/revisions"}],"predecessor-version":[{"id":22806,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/posts\/4129\/revisions\/22806"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/media?parent=4129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/categories?post=4129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcmanrique.org\/de\/wp-json\/wp\/v2\/tags?post=4129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}