{"id":20298,"date":"2019-09-06T08:02:36","date_gmt":"2019-09-06T08:02:36","guid":{"rendered":"https:\/\/fcmanrique.org\/?post_type=fcm_c_agenda&#038;p=20298"},"modified":"2023-01-31T11:24:00","modified_gmt":"2023-01-31T11:24:00","slug":"cesar-manrique-es-un-placer","status":"publish","type":"fcm_c_agenda","link":"https:\/\/fcmanrique.org\/en\/fcm-c-agenda\/cesar-manrique-es-un-placer\/","title":{"rendered":"C\u00e9sar Manrique. Es un placer"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/fcmanrique.org\/es\/wp-json\/wp\/v2\/fcm_c_agenda\/20298\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"ES\">ES<\/a>.<\/p><p>Exposici\u00f3n<em>: C\u00e9sar Manrique. Es un placer. (Un icono popular del siglo XX)<\/em><\/p>\n<p>Taro de Tah\u00edche, Fundaci\u00f3n C\u00e9sar Manrique<\/p>\n<p>Exposici\u00f3n que muestra los diversos rasgos que conformaron el personaje polifac\u00e9tico de C\u00e9sar Manrique hasta construir un icono social y medi\u00e1tico en los a\u00f1os setenta y ochenta del pasado siglo.<\/p>\n<p>Apertura al p\u00fablico: 30 de octubre, 19:00 h.<\/p>\n<p><strong>La exposici\u00f3n permanecer\u00e1 abierta al p\u00fablico<\/strong><strong>&nbsp;en horario de museo: de lunes a domingo, de 10 a 18 horas.<\/strong><\/p>\n<p>Esta muestra \u00fanica y singular, producida por la FCM como su exposici\u00f3n central del Centenario, explora \u201cel proceso de construcci\u00f3n de Manrique como personaje p\u00fablico\u201d, a trav\u00e9s de una intensa proyecci\u00f3n medi\u00e1tica, asociado a Lanzarote y a su casa Taro de Tah\u00edche, \u201cdonde desarroll\u00f3 una est\u00e9tica del placer que transform\u00f3 el arte en vida y la vida en arte de habitar\u201d.<\/p>\n<p>M\u00e1s de 400 fotograf\u00edas, tanto de la esfera p\u00fablica como privada del artista, y un total de 17 audiovisuales, componen el grueso de esta exposici\u00f3n de gran formato, que ocupa una superficie total de 1.600 metros cuadrados.<\/p>\n<p>Asimismo, se exhiben reproducciones de sus m\u00e1scaras del Carnaval, cer\u00e1micas que dise\u00f1\u00f3 en los a\u00f1os cincuenta, cuadros pintados por el artista; se ambientan distintas estancias de su casa Taro de Tah\u00edche; y se muestran numerosos objetos pertenecientes al creador de los Jameos del Agua (maniqu\u00edes, libros, prendas de vestir, esculturas africanas\u2026), diarios personales, carteles originales de sus exposiciones tanto nacionales como internacionales, reportajes de revistas, postales de sus viajes y \u00e1lbumes-<em>collage<\/em> de gran tama\u00f1o realizados por el artista.<\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-inauguracion-exposicion-su-majestad-el-rey.pdf\">M\u00e1s informaci\u00f3n Exposici\u00f3n C\u00e9sar Manrique. Es un placer<\/a><\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20705\" src=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer.jpg 1200w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer-150x150.jpg 150w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer-300x300.jpg 300w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer-768x768.jpg 768w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer-1024x1024.jpg 1024w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-exposicion-cm-placer-246x246.jpg 246w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-triptico-ex-exposicion-cesar-manrique-es-un-placer.pdf\">Tr\u00edptico informativo de la exposici\u00f3n (exterior)<\/a><\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-triptico-int-exposicion-cesar-manrique-es-un-placer.pdf\">Tr\u00edptico informativo de la exposici\u00f3n (interior)<\/a><\/p>\n<p>Cr\u00f3nica de la inauguraci\u00f3n oficial:<\/p>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" title=\"\u00abInauguraci\u00f3n de exposici\u00f3n \u00abC\u00e9sar Manrique. Es un placer\u00bb, presidida por Su Majestad el Rey \u00bb \u2014 Fundaci\u00f3n C\u00e9sar Manrique\" src=\"https:\/\/fcmanrique.org\/fcm-c-acti-celebrada\/inauguracion-de-exposicion-cesar-manrique-es-un-placer-presidida-por-su-majestad-el-rey\/embed\/#?secret=WUyyv2SeEC\" width=\"600\" height=\"325\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-scripts\" data-secret=\"WUyyv2SeEC\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>Cr\u00f3nica de la apertura al p\u00fablico de la exposici\u00f3n:<\/p>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" title=\"\u00abApertura al p\u00fablico de la exposici\u00f3n \u00abC\u00e9sar Manrique. Es un placer\u00bb\u00bb \u2014 Fundaci\u00f3n C\u00e9sar Manrique\" src=\"https:\/\/fcmanrique.org\/fcm-c-acti-celebrada\/apertura-al-publico-de-la-exposicion-cesar-manrique-es-un-placer\/embed\/#?secret=fqcZXR8qTo\" width=\"600\" height=\"325\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-scripts\" data-secret=\"fqcZXR8qTo\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>&nbsp;<\/p>","protected":false},"parent":0,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-20298","fcm_c_agenda","type-fcm_c_agenda","status-publish","hentry","c_agenda_categoria-exposicion"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_c_agenda\/20298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_c_agenda"}],"about":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/types\/fcm_c_agenda"}],"version-history":[{"count":19,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_c_agenda\/20298\/revisions"}],"predecessor-version":[{"id":23274,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_c_agenda\/20298\/revisions\/23274"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/media?parent=20298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}