{"id":14596,"date":"2018-02-15T23:34:02","date_gmt":"2018-02-15T23:34:02","guid":{"rendered":"https:\/\/fcmanrique.org\/fcm-obra\/nils-udo-sin-titulo\/"},"modified":"2022-10-10T10:46:45","modified_gmt":"2022-10-10T10:46:45","slug":"nils-udo-sin-titulo","status":"publish","type":"fcm_obra","link":"https:\/\/fcmanrique.org\/en\/fcm-obra\/nils-udo-sin-titulo\/","title":{"rendered":"Nils-Udo. Sin t\u00edtulo"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/fcmanrique.org\/es\/wp-json\/wp\/v2\/fcm_obra\/14596\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"ES\">ES<\/a>.<\/p><p><strong>Programa \u00abResidencia-Taller. Artistas en residencia\u00bb organizado por la Fundaci\u00f3n C\u00e9sar Manrique<\/strong><\/p>\n<p>Nils-Udo particip\u00f3 en el programa &#8220;Residencia-Taller. Artistas en residencia&#8221; en el a\u00f1o 2002, un a\u00f1o despu\u00e9s de que la FCM acogiera la exposici\u00f3n itinerante dedicada al artista alem\u00e1n.<\/p>\n<p>Desde el d\u00eda 10 de junio hasta finales de ese mismo mes, realiz\u00f3 diversas obras art\u00edsticas relacionadas con el paisaje de Lanzarote, apoyado por un equipo de asistentes proporcionado por la instituci\u00f3n.<\/p>\n<p>En las delicadas y ef\u00edmeras manipulaciones de la naturaleza que realiz\u00f3, posteriormente fotografiadas, emple\u00f3 sal, piedras, rofe, flores, bamb\u00fa y hojas de palmera conviviendo con el cielo y el mar de la isla.<\/p>\n<p>Nils-Udo, que trabaj\u00f3 en el Calet\u00f3n Blanco, Las Malvas (Tinajo), La Maleza, Tao y Teseguite, realiz\u00f3 diversas creaciones en el paisaje de Lanzarote de las cuales la FCM adquiri\u00f3 7 para su colecci\u00f3n Arte-Naturaleza.<\/p>","protected":false},"featured_media":14597,"parent":0,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"tipo_de_obra":[],"coleccion_de_obra":[21],"class_list":["post-14596","fcm_obra","type-fcm_obra","status-publish","has-post-thumbnail","hentry","coleccion_de_obra-arte-y-naturaleza"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_obra\/14596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_obra"}],"about":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/types\/fcm_obra"}],"version-history":[{"count":1,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_obra\/14596\/revisions"}],"predecessor-version":[{"id":23165,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/fcm_obra\/14596\/revisions\/23165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/media\/14597"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/media?parent=14596"}],"wp:term":[{"taxonomy":"tipo_de_obra","embeddable":true,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/tipo_de_obra?post=14596"},{"taxonomy":"coleccion_de_obra","embeddable":true,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/coleccion_de_obra?post=14596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}