{"id":4126,"date":"2008-02-18T00:00:00","date_gmt":"2008-02-18T00:00:00","guid":{"rendered":"https:\/\/fcmanrique.org\/2008\/02\/18\/nueva-sentencia-favorable-a-la-fcm-anula-licencia-a-hotel-de-400-plazas-en-playa-blanca\/?lang=es"},"modified":"2022-09-13T10:05:59","modified_gmt":"2022-09-13T10:05:59","slug":"nueva-sentencia-favorable-a-la-fcm-anula-licencia-a-hotel-de-400-plazas-en-playa-blanca","status":"publish","type":"post","link":"https:\/\/fcmanrique.org\/en\/nueva-sentencia-favorable-a-la-fcm-anula-licencia-a-hotel-de-400-plazas-en-playa-blanca\/","title":{"rendered":"Nueva sentencia favorable a la FCM anula licencia a hotel de 400 plazas en Playa Blanca"},"content":{"rendered":"<p><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El Juzgado de lo Contencioso-Administrativo n&ordm; 2 de Las Palmas de Gran Canaria emiti&oacute; en diciembre una sentencia en las que estima el recursos presentado por la Fundaci&oacute;n C&eacute;sar Manrique contra la licencia concedida por el Ayuntamiento de Yaiza a un hotel de 400 plazas en Playa Blanca.<\/p>\n<p>M&aacute;s informaci&oacute;n en la nota de prensa.<\/span><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El Juzgado de lo Contencioso-Administrativo n&ordm; 2 de Las Palmas de Gran Canaria emiti&oacute; en diciembre una sentencia en las que estima el recursos presentado por la Fundaci&oacute;n C&eacute;sar Manrique contra la licencia concedida por el Ayuntamiento de Yaiza a un hotel de 400 plazas en Playa Blanca.<\/p>\n<p>M&aacute;s informaci&oacute;n en la nota de prensa.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">El Juzgado de lo Contencioso-Administrativo n&ordm; 2 de Las Palmas de Gran Canaria emiti&oacute; en diciembre una sentencia en las que estima el recursos presentado por la Fundaci&oacute;n C&eacute;sar Manrique contra la licencia concedida por el Ayuntamiento de Yaiza a un hotel de 400 plazas en Playa Blanca.<o:p><\/o:p><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,77,4],"tags":[],"class_list":["post-4126","post","type-post","status-publish","format-standard","hentry","category-sitio-antiguo","category-prensa","category-expirados"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/posts\/4126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/comments?post=4126"}],"version-history":[{"count":4,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/posts\/4126\/revisions"}],"predecessor-version":[{"id":22807,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/posts\/4126\/revisions\/22807"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/media?parent=4126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/categories?post=4126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcmanrique.org\/en\/wp-json\/wp\/v2\/tags?post=4126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}