{"id":19243,"date":"2019-05-23T13:48:30","date_gmt":"2019-05-23T13:48:30","guid":{"rendered":"https:\/\/fcmanrique.org\/?post_type=fcm_c_ev_relac&#038;p=19243"},"modified":"2019-05-28T13:39:04","modified_gmt":"2019-05-28T13:39:04","slug":"prehistoria-futurista-articulo-publicado-en-la-revista-arquitectura-viva","status":"publish","type":"fcm_c_ev_relac","link":"https:\/\/fcmanrique.org\/fr\/fcm-c-ev-relac\/prehistoria-futurista-articulo-publicado-en-la-revista-arquitectura-viva\/","title":{"rendered":"Prehistoria futurista. Art\u00edculo publicado en la revista AV"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/fcmanrique.org\/es\/wp-json\/wp\/v2\/fcm_c_ev_relac\/19243\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"ES\">ES<\/a>.<\/p><p><em><strong>Prehistoria futurista. C\u00e9sar Manrique, a Centenary Master<\/strong><\/em><\/p>\n<p>Publicado en la revista Arquitectura Viva, n\u00famero 213, abril 2019.<\/p>\n<p>La casa-cueva que C\u00e9sar Manrique comenz\u00f3 a levantar en 1968 en Lanzarote desarrolla los requisitos de un programa autobiogr\u00e1fico mientras desborda la arquitectura. Terence Riley percibi\u00f3 Taro de Tah\u00edche como \u00a0\u00bbun sue\u00f1o de Jung\u00a0\u00bb. El propio artista la interpret\u00f3 como parte de su identidad: \u00a0\u00bbes una prlongaci\u00f3n de m\u00ed mismo\u00a0\u00bb.<\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19247\" src=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva2-1.jpg\" alt=\"\" width=\"1247\" height=\"2033\" srcset=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva2-1.jpg 1247w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva2-1-184x300.jpg 184w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva2-1-768x1252.jpg 768w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva2-1-628x1024.jpg 628w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva2-1-151x246.jpg 151w\" sizes=\"auto, (max-width: 1247px) 100vw, 1247px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19248\" src=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva1-1.jpg\" alt=\"\" width=\"1657\" height=\"2142\" srcset=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva1-1.jpg 1657w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva1-1-232x300.jpg 232w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva1-1-768x993.jpg 768w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva1-1-792x1024.jpg 792w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-arquitectura-viva1-1-190x246.jpg 190w\" sizes=\"auto, (max-width: 1657px) 100vw, 1657px\" \/><\/a><\/p>\n<p>M\u00e1s informaci\u00f3n en:\u00a0<a href=\"http:\/\/www.arquitecturaviva.com\/es\/Shop\/Issue\/Details\/488\">http:\/\/www.arquitecturaviva.com\/es\/Shop\/Issue\/Details\/488<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en ES.Prehistoria futurista. C\u00e9sar Manrique, a Centenary Master Publicado en la revista Arquitectura Viva, n\u00famero 213, abril 2019. La casa-cueva que C\u00e9sar Manrique comenz\u00f3 a levantar en 1968 en Lanzarote desarrolla los requisitos de un programa autobiogr\u00e1fico mientras desborda la arquitectura. Terence Riley percibi\u00f3 Taro de Tah\u00edche como \u00a0\u00bbun&#8230; <a href=\"https:\/\/fcmanrique.org\/fr\/fcm-c-ev-relac\/prehistoria-futurista-articulo-publicado-en-la-revista-arquitectura-viva\/\" class=\"readmore\">Contin\u00faa leyendo \u2192<\/a><\/p>\n","protected":false},"featured_media":19244,"parent":0,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-19243","fcm_c_ev_relac","type-fcm_c_ev_relac","status-publish","has-post-thumbnail","hentry","c_ev_relac_categoria-prensa-nacional"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/fcm_c_ev_relac\/19243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/fcm_c_ev_relac"}],"about":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/types\/fcm_c_ev_relac"}],"version-history":[{"count":14,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/fcm_c_ev_relac\/19243\/revisions"}],"predecessor-version":[{"id":19340,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/fcm_c_ev_relac\/19243\/revisions\/19340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/media\/19244"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/media?parent=19243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}