{"id":22190,"date":"2020-04-24T15:41:37","date_gmt":"2020-04-24T15:41:37","guid":{"rendered":"https:\/\/fcmanrique.org\/?p=22190"},"modified":"2022-09-26T11:44:29","modified_gmt":"2022-09-26T11:44:29","slug":"concluye-actividades-centenario-cesar-manrique","status":"publish","type":"post","link":"https:\/\/fcmanrique.org\/fr\/concluye-actividades-centenario-cesar-manrique\/","title":{"rendered":"Concluye el ciclo de actividades del centenario de C\u00e9sar Manrique"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/fcmanrique.org\/es\/wp-json\/wp\/v2\/posts\/22190\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"ES\">ES<\/a>.<\/p><p>Hace un a\u00f1o que la FCM comenz\u00f3 a conmemorar el centenario del nacimiento de C\u00e9sar Manrique. Un a\u00f1o repleto de actividades culturales, medioambientales, art\u00edsticas y l\u00fadicas, compartidas con miles de asistentes a los que les damos las gracias por su cari\u00f1o y apoyo. A pesar de la adversidad que a todos nos golpea, y que ha irrumpido de forma abrupta en nuestras vidas, la Fundaci\u00f3n seguir\u00e1 trabajando para que el legado creativo y el pensamiento ambientalista del artista perdure e ilumine el futuro de las generaciones venideras.<\/p>\n<p>Despedimos el a\u00f1o de su centenario recordando unas palabras suyas que celebran la vida, hoy m\u00e1s que nunca un bien com\u00fan en riesgo: \u201cLa vida es un espect\u00e1culo \u00fanico y el hombre a veces no es consciente de su significado. Cree que va a vivir dos mil a\u00f1os, pero la vida es corta, muy corta, cort\u00edsima. Tenemos que aprovecharla\u201d. Para vivir la vida con dignidad y plenitud es imprescindible respetarla y cuidarla en toda su amplitud humana y planetaria. Hoy bien lo sabemos. Cuidemos la Tierrra, cuidemos de nosotros: \u00a1Juntos, por la vida!<\/p>\n<p>Visitar la web del centenario: <a href=\"https:\/\/fcmanrique.org\/centenario\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/fcmanrique.org\/centenario<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en ES.Hace un a\u00f1o que la FCM comenz\u00f3 a conmemorar el centenario del nacimiento de C\u00e9sar Manrique. Un a\u00f1o repleto de actividades culturales, medioambientales, art\u00edsticas y l\u00fadicas, compartidas con miles de asistentes a los que les damos las gracias por su cari\u00f1o y apoyo. A pesar de la adversidad&#8230; <a href=\"https:\/\/fcmanrique.org\/fr\/concluye-actividades-centenario-cesar-manrique\/\" class=\"readmore\">Contin\u00faa leyendo \u2192<\/a><\/p>\n","protected":false},"author":1,"featured_media":22202,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-22190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts\/22190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/comments?post=22190"}],"version-history":[{"count":3,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts\/22190\/revisions"}],"predecessor-version":[{"id":22197,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts\/22190\/revisions\/22197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/media\/22202"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/media?parent=22190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/categories?post=22190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/tags?post=22190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}