{"id":4110,"date":"2008-03-14T00:00:00","date_gmt":"2008-03-14T00:00:00","guid":{"rendered":"https:\/\/fcmanrique.org\/2008\/03\/14\/el-tsjc-ratifica-dos-sentencias-contra-licencias-otorgadas-por-los-ayuntamientos-de-yaiza-y-teguise\/?lang=es"},"modified":"2022-09-13T11:51:12","modified_gmt":"2022-09-13T11:51:12","slug":"el-tsjc-ratifica-dos-sentencias-contra-licencias-otorgadas-por-los-ayuntamientos-de-yaiza-y-teguise","status":"publish","type":"post","link":"https:\/\/fcmanrique.org\/fr\/el-tsjc-ratifica-dos-sentencias-contra-licencias-otorgadas-por-los-ayuntamientos-de-yaiza-y-teguise\/","title":{"rendered":"El TSJC ratifica dos sentencias contra licencias otorgadas por los ayuntamientos de Yaiza y Teguise"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\" class=\"MsoNormal\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">La Secci&oacute;n Segunda de la Sala de lo Contencioso Administrativo del Tribunal Superior de Justicia de Canarias (TSJC) emiti&oacute; el pasado mes de febrero dos autos en los que ha ratificado las sentencias dictadas en 2007, favorables a la Fundaci&oacute;n C&eacute;sar Manrique, por las que anul&oacute; las licencias concedidas por los Ayuntamientos de Yaiza y Teguise para la construcci&oacute;n de un hotel y un complejo de apartamentos, respectivamente.<o:p><\/o:p><\/span><\/p>\n<p>M&aacute;s informaci&oacute;n en la nota de prensa.<\/p>\n<p style=\"text-align: justify;\" class=\"MsoNormal\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">La Secci&oacute;n Segunda de la Sala de lo Contencioso Administrativo del Tribunal Superior de Justicia de Canarias (TSJC) emiti&oacute; el pasado mes de febrero dos autos en los que ha ratificado las sentencias dictadas en 2007, favorables a la Fundaci&oacute;n C&eacute;sar Manrique, por las que anul&oacute; las licencias concedidas por los Ayuntamientos de Yaiza y Teguise para la construcci&oacute;n de un hotel y un complejo de apartamentos, respectivamente.<o:p><\/o:p><\/span><\/p>\n<p>M&aacute;s informaci&oacute;n en la nota de prensa.<\/p>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\" class=\"MsoNormal\"><span style=\"ofont-size: 10pt; ofont-family: Arial;\">La Secci&oacute;n Segunda de la Sala de lo Contencioso Administrativo del Tribunal Superior de Justicia de Canarias (TSJC) emiti&oacute; el pasado mes de febrero dos autos en los que ha ratificado las sentencias dictadas en 2007, favorables a la Fundaci&oacute;n C&eacute;sar Manrique, por las que anul&oacute; las licencias concedidas por los Ayuntamientos de Yaiza y Teguise para la construcci&oacute;n de un hotel y un complejo de apartamentos, respectivamente.<o:p><\/o:p><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,77,4],"tags":[],"class_list":["post-4110","post","type-post","status-publish","format-standard","hentry","category-sitio-antiguo","category-prensa","category-expirados"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts\/4110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/comments?post=4110"}],"version-history":[{"count":4,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts\/4110\/revisions"}],"predecessor-version":[{"id":22811,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/posts\/4110\/revisions\/22811"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/media?parent=4110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/categories?post=4110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcmanrique.org\/fr\/wp-json\/wp\/v2\/tags?post=4110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}