{"id":27759,"date":"2026-05-04T11:50:47","date_gmt":"2026-05-04T11:50:47","guid":{"rendered":"https:\/\/fcmanrique.org\/?post_type=fcm_video&#038;p=27759"},"modified":"2026-05-11T10:19:59","modified_gmt":"2026-05-11T10:19:59","slug":"luis-antonio-de-villena-un-nuevo-paganismo","status":"publish","type":"fcm_video","link":"https:\/\/fcmanrique.org\/it\/fcm-video\/luis-antonio-de-villena-un-nuevo-paganismo\/","title":{"rendered":"Luis Antonio de Villena: \u00abUn nuevo paganismo\u00bb"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-it\">Ci spiace, ma questo articolo \u00e8 disponibile soltanto in <a href=\"https:\/\/fcmanrique.org\/es\/wp-json\/wp\/v2\/fcm_video\/27759\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"ES\">ES<\/a>.<\/p><p><\/p>\n<p><strong>El autor y su obra<\/strong><\/p>\n<p>La Fundaci\u00f3n C\u00e9sar Manrique (FCM) acogi\u00f3 el pasado 7 de mayo de 2026, la conferencia titulada \u201cUn nuevo paganismo\u201d, que fue impartida por Luis Antonio de Villena, uno de los poetas, narradores y ensayistas m\u00e1s prol\u00edficos de la literatura espa\u00f1ola contempor\u00e1nea. El acto tuvo lugar en la Sala Jos\u00e9 Saramago (La Plazuela, Arrecife) y tambi\u00e9n fue transmitido en directo a trav\u00e9s de la web y el canal de Youtube de la FCM.<\/p>\n<p>Durante su intervenci\u00f3n, De Villena \u2014Premio Nacional de la Cr\u00edtica en la categor\u00eda poes\u00eda (1981) por Huir del invierno y Premio Azor\u00edn de Novela (1995) por su obra El burdel de Lord Byron\u2014 traslad\u00f3 su aspiraci\u00f3n personal a favor de un paganismo nuevo que, en amplio sentido, sirva de contraposici\u00f3n a los dogmas establecidos. Lo hizo acompa\u00f1ado de una lectura po\u00e9tica en la que, adem\u00e1s, evoc\u00f3 a C\u00e9sar Manrique desde el inicio.<\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong>&nbsp;<a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fcmanrique-nota-prensa-villena.pdf\" target=\"_blank\" rel=\"noopener\">Nota de prensa<\/a><\/p>\n<p><strong>Cr\u00f3nica de la conferencia:<\/strong>&nbsp;<a href=\"https:\/\/fcmanrique.org\/fcm-actividad\/luis-antonio-de-villena-la-libertad-colectiva-es-la-union-de-muchas-libertades-individuales\/?cpg=0\" target=\"_blank\" rel=\"noopener\">Cr\u00f3nica<\/a><\/p>","protected":false},"featured_media":27823,"parent":0,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"video_coleccion":[],"class_list":["post-27759","fcm_video","type-fcm_video","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/fcm_video\/27759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/fcm_video"}],"about":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/types\/fcm_video"}],"version-history":[{"count":17,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/fcm_video\/27759\/revisions"}],"predecessor-version":[{"id":27855,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/fcm_video\/27759\/revisions\/27855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/media\/27823"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/media?parent=27759"}],"wp:term":[{"taxonomy":"video_coleccion","embeddable":true,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/video_coleccion?post=27759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}