{"id":18087,"date":"2019-03-21T09:42:02","date_gmt":"2019-03-21T09:42:02","guid":{"rendered":"https:\/\/fcmanrique.org\/?p=18087"},"modified":"2019-05-16T11:04:22","modified_gmt":"2019-05-16T11:04:22","slug":"la-fcm-rechaza-la-instalacion-de-vallas-publicitarias-por-geoparque-lanzarote","status":"publish","type":"post","link":"https:\/\/fcmanrique.org\/it\/la-fcm-rechaza-la-instalacion-de-vallas-publicitarias-por-geoparque-lanzarote\/","title":{"rendered":"La FCM rechaza la instalaci\u00f3n de vallas publicitarias por Geoparque Lanzarote"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-it\">Ci spiace, ma questo articolo \u00e8 disponibile soltanto in <a href=\"https:\/\/fcmanrique.org\/es\/wp-json\/wp\/v2\/posts\/18087\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"ES\">ES<\/a>.<\/p><p>La Fundaci\u00f3n C\u00e9sar Manrique comunica a la opini\u00f3n p\u00fablica su rechazo a las vallas publicitarias colocadas en diversos puntos de la isla por Geoparque Lanzarote y Archipi\u00e9lago Chinijo.<\/p>\n<p>Evitar o mitigar el impacto de los soportes publicitarios en el territorio constituy\u00f3 un componente est\u00e9tico y simb\u00f3lico significativo del modelo paisaj\u00edstico singular que impuls\u00f3 C\u00e9sar Manrique. Proteger y mantener la isla libre del impacto visual de vallas publicitarias fue un empe\u00f1o del artista que defendi\u00f3 con u\u00f1as y dientes, del que siempre se sinti\u00f3 orgulloso, como dej\u00f3 testimonio en numerosas declaraciones p\u00fablicas. De hecho, hasta hace algunos a\u00f1os, la inexistencia de soportes publicitarios en los m\u00e1rgenes del viario fue reconocida como un valor a\u00f1adido y distintivo del patrimonio cultural y paisaj\u00edstico insular en el contexto de la industria tur\u00edstica. Y lo es hasta tal punto de que su prohibici\u00f3n en suelo r\u00fastico est\u00e1 recogida en la normativa del Plan Insular vigente, en este caso incumplida por Geoparque. Una paradoja verdaderamente chocante. Asimismo, la instalaci\u00f3n de vallas publicitarias fuera de los tramos urbanos est\u00e1 tambi\u00e9n prohibida&nbsp; por la Ley de Carreteras de Canarias.<\/p>\n<div id=\"attachment_18088\" class=\"wp-caption alignnone\" style=\"max-width: 810px;\"><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-18088\" src=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque1.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque1.jpg 800w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque1-300x225.jpg 300w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque1-768x576.jpg 768w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque1-289x217.jpg 289w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><p class=\"wp-caption-text\">dav<\/p><\/div>\n<p>Lanzarote adolece de un problema acusado y creciente en lo que concierne al impacto y desorden visual causado por anuncios publicitarios, sobre todo en entornos urbanos y zonas industriales, que afean el paisaje y contribuyen a la p\u00e9rdida de identidad de la isla. Un problema que reclama una decisiva y urgente actuaci\u00f3n por parte de los ayuntamientos y el Cabildo para aplicar y hacer cumplir las ordenanzas y normativas existentes, adem\u00e1s de a\u00f1adir las que fueran necesarias con el prop\u00f3sito de poner remedio a una degradaci\u00f3n paulatina y alarmante que empeora la calidad del paisaje natural y urbano de Lanzarote y erosiona su identidad hist\u00f3rica moderna reciente, tal y como ha venido denunciando la Fundaci\u00f3n C\u00e9sar Manrique.&nbsp;<\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18089\" src=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque2.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque2.jpg 1280w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque2-300x225.jpg 300w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque2-768x576.jpg 768w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque2-1024x768.jpg 1024w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque2-289x217.jpg 289w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p>A la Fundaci\u00f3n C\u00e9sar Manrique le resulta particularmente decepcionante y triste que Geoparque Lanzarote y Archipi\u00e9lago Chinijo, responsable de administrar una figura destinada a un \u201cterritorio caracterizado por un patrimonio geol\u00f3gico de importancia internacional, gestionado con criterios de protecci\u00f3n, educaci\u00f3n y desarrollo sostenible\u201d, renuncie a la cultura de protecci\u00f3n del paisaje que C\u00e9sar Manrique luch\u00f3 por mantener ajeno&nbsp; a&nbsp; las vallas, y, con esta desafortunada actuaci\u00f3n publicitaria, se sume al desorden y los impactos negativos de la publicidad en espacios urbanos y rurales. Resulta especialmente penoso que este hecho insensible suceda en el a\u00f1o en que se conmemora el centenario del artista, una circunstancia que deber\u00eda invitar, sobre todo a las administraciones p\u00fablicas insulares, a respetar su obra y seguir sus pasos honrando verdaderamente su memoria y su legado, material e inmaterial, que tanto prestigio y beneficios han proporcionado a la isla y a sus ciudadanos.<\/p>\n<p><a href=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18090\" src=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque3.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque3.jpg 1280w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque3-300x225.jpg 300w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque3-768x576.jpg 768w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque3-1024x768.jpg 1024w, https:\/\/fcmanrique.org\/wp-content\/uploads\/fc-manrique-valla-geoparque3-289x217.jpg 289w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p>Por consiguiente, en la fecha en que se conmemoran cien a\u00f1os de vida de C\u00e9sar Manrique, proceder\u00eda, y as\u00ed lo demanda la Fundaci\u00f3n que lleva su nombre, que se retiren inmediatamente las desafortunadas e inadmisibles vallas publicitarias de Geoparque Lanzarote instaladas en diversos puntos, una conducta que desacredita las tareas de un Geoparque propio de nuestra isla, banaliza el paisaje, desfigura un gran legado y agravia la memoria de C\u00e9sar Manrique.&nbsp; &nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Ci spiace, ma questo articolo \u00e8 disponibile soltanto in ES.La Fundaci\u00f3n C\u00e9sar Manrique comunica a la opini\u00f3n p\u00fablica su rechazo a las vallas publicitarias colocadas en diversos puntos de la isla por Geoparque Lanzarote y Archipi\u00e9lago Chinijo. Evitar o mitigar el impacto de los soportes publicitarios en el territorio constituy\u00f3 un componente est\u00e9tico y simb\u00f3lico&#8230; <a href=\"https:\/\/fcmanrique.org\/it\/la-fcm-rechaza-la-instalacion-de-vallas-publicitarias-por-geoparque-lanzarote\/\" class=\"readmore\">Contin\u00faa leyendo \u2192<\/a><\/p>\n","protected":false},"author":2,"featured_media":18088,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[77],"tags":[],"class_list":["post-18087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"acf":[],"_links":{"self":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/posts\/18087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/comments?post=18087"}],"version-history":[{"count":1,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/posts\/18087\/revisions"}],"predecessor-version":[{"id":18091,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/posts\/18087\/revisions\/18091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/media\/18088"}],"wp:attachment":[{"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/media?parent=18087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/categories?post=18087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fcmanrique.org\/it\/wp-json\/wp\/v2\/tags?post=18087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}